{"id":3121,"date":"2022-04-19T09:23:24","date_gmt":"2022-04-19T09:23:24","guid":{"rendered":"https:\/\/www.stalskog.se\/?page_id=3121"},"modified":"2025-08-25T14:22:36","modified_gmt":"2025-08-25T14:22:36","slug":"geschaeftsleitbild-grundsaetze","status":"publish","type":"page","link":"https:\/\/www.stalskog.se\/de\/ueber-uns\/geschaeftsleitbild-grundsaetze\/","title":{"rendered":"Gesch\u00e4ftskonzept\/Politik"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3121\" class=\"elementor elementor-3121 elementor-3014\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-652507b elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"652507b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-28b2df0\" data-id=\"28b2df0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e7757d5 elementor-widget elementor-widget-heading\" data-id=\"e7757d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">GESCH\u00c4FTSKONZEPT \/ POLITIK<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b70b468 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b70b468\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7a656c3\" data-id=\"7a656c3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6cc22d4 elementor-widget elementor-widget-shortcode\" data-id=\"6cc22d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"15065\" class=\"elementor elementor-15065 elementor-1919 elementor-1919\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1443c7ba elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"1443c7ba\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-35100657\" data-id=\"35100657\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bfe333f elementor-widget elementor-widget-woocommerce-breadcrumb\" data-id=\"bfe333f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-breadcrumb.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<nav class=\"woocommerce-breadcrumb\" aria-label=\"Breadcrumb\">Start<\/nav>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b61e97c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b61e97c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1aabd3f\" data-id=\"1aabd3f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f02cfcb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f02cfcb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1c7b89e\" data-id=\"1c7b89e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4505915 elementor-widget elementor-widget-heading\" data-id=\"4505915\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gesch\u00e4ftskonzept<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9908438 elementor-widget__width-initial elementor-widget-tablet__width-inherit half-text-space-left elementor-widget elementor-widget-text-editor\" data-id=\"9908438\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Produkte des Unternehmens m\u00fcssen die sichersten und erschwinglichsten auf dem Markt sein und als solche wahrgenommen werden. Mit unserem langfristigen Engagement f\u00fcr Produktqualit\u00e4t, Produktentwicklung, Service und Fachwissen geben wir unseren Kunden die Sicherheit, die Ragnar St\u00e5lskog AB zu ihrer ersten Wahl macht.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1a506d8\" data-id=\"1a506d8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5cb77ec elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-image\" data-id=\"5cb77ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.stalskog.se\/wp-content\/uploads\/2022\/04\/ISO-9001-SWE_Ragnar_Stalskog_AB.png\" target=\"_blank\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"708\" height=\"1000\" src=\"https:\/\/www.stalskog.se\/wp-content\/uploads\/2022\/04\/ISO-9001-SWE_Ragnar_Stalskog_AB.png\" class=\"attachment-large size-large wp-image-12560\" alt=\"\" srcset=\"https:\/\/www.stalskog.se\/wp-content\/uploads\/2022\/04\/ISO-9001-SWE_Ragnar_Stalskog_AB.png 708w, https:\/\/www.stalskog.se\/wp-content\/uploads\/2022\/04\/ISO-9001-SWE_Ragnar_Stalskog_AB-212x300.png 212w, https:\/\/www.stalskog.se\/wp-content\/uploads\/2022\/04\/ISO-9001-SWE_Ragnar_Stalskog_AB-300x424.png 300w, https:\/\/www.stalskog.se\/wp-content\/uploads\/2022\/04\/ISO-9001-SWE_Ragnar_Stalskog_AB-600x847.png 600w\" sizes=\"(max-width: 708px) 100vw, 708px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0ac0374 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0ac0374\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3ece013\" data-id=\"3ece013\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c2993fe elementor-widget elementor-widget-heading\" data-id=\"c2993fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">POLITIK<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-511c9f5 elementor-widget__width-initial elementor-widget-tablet__width-inherit half-text-space-left elementor-widget elementor-widget-text-editor\" data-id=\"511c9f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Qualit\u00e4t sowohl der Produkte als auch der Arbeitsabl\u00e4ufe ist f\u00fcr Unternehmen, die auf dem Markt wettbewerbsf\u00e4hig sein wollen, von entscheidender Bedeutung.<\/p><p>Zur Sicherstellung und weiteren Verbesserung der Produkte und Abl\u00e4ufe hat Ragnar St\u00e5lskog AB sein Qualit\u00e4tsmanagementsystem nach SS-EN ISO 9001 und sein Umweltmanagementsystem nach SS-EN ISO 14001 zertifiziert.<\/p><p>Die folgenden Richtlinien verdeutlichen die Herangehensweise und das Verhalten des Unternehmens in Bezug auf GDPR, Ethik, Qualit\u00e4t und Umweltfragen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f07d2ec\" data-id=\"f07d2ec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-31ea566 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"31ea566\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7e673a5\" data-id=\"7e673a5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb22634 elementor-widget elementor-widget-heading\" data-id=\"fb22634\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Datenschutzrichtlinie - GDPR<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c4bbe1 elementor-widget elementor-widget-heading\" data-id=\"0c4bbe1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ethik-Politik  <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb013ef elementor-widget__width-initial elementor-widget-tablet__width-inherit half-text-space-left elementor-widget elementor-widget-text-editor\" data-id=\"fb013ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir werden uns bem\u00fchen, von unseren Stakeholdern als solides und erfolgreiches Unternehmen wahrgenommen zu werden, das mit hoher Integrit\u00e4t und Moral gef\u00fchrt wird.<\/p><p>Als Unternehmen und Lieferant stellt Ragnar St\u00e5lskog AB sicher, dass unsere Lieferanten die Gesetze und Vorschriften einhalten, die in den L\u00e4ndern gelten, in denen die Gesch\u00e4fte get\u00e4tigt werden, und dass sie<br>die Menschenrechtserkl\u00e4rung der Vereinten Nationen respektieren.<\/p><p>Ragnar St\u00e5lskog AB ist bestrebt, eine tadellose Gesch\u00e4ftsethik zu haben, und Bestechung und Korruption d\u00fcrfen in den Gesch\u00e4ftsbeziehungen des Unternehmens niemals vorkommen.<\/p><p>Wir werden sicherstellen, dass in unserer Produktion keine Konfliktmineralien verwendet werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-431c568\" data-id=\"431c568\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce170ff elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-image\" data-id=\"ce170ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.stalskog.se\/wp-content\/uploads\/2022\/04\/ISO-1401-SWE_Ragnar_Stalskog_AB.jpg\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"707\" height=\"1000\" src=\"https:\/\/www.stalskog.se\/wp-content\/uploads\/2022\/04\/ISO-1401-SWE_Ragnar_Stalskog_AB.jpg\" class=\"attachment-large size-large wp-image-12565\" alt=\"\" srcset=\"https:\/\/www.stalskog.se\/wp-content\/uploads\/2022\/04\/ISO-1401-SWE_Ragnar_Stalskog_AB.jpg 707w, https:\/\/www.stalskog.se\/wp-content\/uploads\/2022\/04\/ISO-1401-SWE_Ragnar_Stalskog_AB-212x300.jpg 212w, https:\/\/www.stalskog.se\/wp-content\/uploads\/2022\/04\/ISO-1401-SWE_Ragnar_Stalskog_AB-300x424.jpg 300w, https:\/\/www.stalskog.se\/wp-content\/uploads\/2022\/04\/ISO-1401-SWE_Ragnar_Stalskog_AB-600x849.jpg 600w\" sizes=\"(max-width: 707px) 100vw, 707px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9e780b5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9e780b5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-dceaf81\" data-id=\"dceaf81\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78dc40d elementor-widget elementor-widget-heading\" data-id=\"78dc40d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Qualit\u00e4tspolitik<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c96b9cf elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"c96b9cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>Wir werden daf\u00fcr sorgen:<\/strong>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd5b3c2 elementor-widget__width-initial elementor-widget-tablet__width-inherit list-items half-text-space-left elementor-widget elementor-widget-text-editor\" data-id=\"cd5b3c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Unsere elektrischen Sicherheitsprodukte, wie Erdungsger\u00e4te, Bedienungsstangen, Rauchmelder, Spannungs- und Phasengleichheitspr\u00fcfer, erf\u00fcllen die h\u00f6chsten Standards in Bezug auf Qualit\u00e4t, Zuverl\u00e4ssigkeit und Benutzerfreundlichkeit.<\/li><li>unsere Produkte und Dienstleistungen die versprochenen Lieferzeiten sowie die vereinbarten Preise und Bedingungen einhalten.<\/li><li>arbeiten und die kontinuierliche Verbesserung innerhalb des Unternehmens f\u00f6rdern, so dass eine hohe Qualit\u00e4t im internen Service, in der Verwaltung, im Verhalten und in den Kundenbeziehungen erreicht wird und dass jede Aufgabe, die wir ausf\u00fchren, eine gute Referenz f\u00fcr zuk\u00fcnftige Gesch\u00e4fte wird.<\/li><li>die aktuellen und zuk\u00fcnftigen Anforderungen und Erwartungen unserer Kunden und Stakeholder in Bezug auf Produkte und Gesch\u00e4ftsbeziehungen zu \u00fcbertreffen, indem wir jeden in die kontinuierliche Verbesserung einbeziehen. Wir streben bei allem, was wir tun, eine Null-Fehler-Qualit\u00e4t an und jeder Mitarbeiter ist f\u00fcr die Qualit\u00e4t seiner Arbeit verantwortlich. <\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5fd7c16\" data-id=\"5fd7c16\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-26357f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"26357f7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-67e6e66\" data-id=\"67e6e66\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c913771 elementor-widget elementor-widget-heading\" data-id=\"c913771\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Umweltpolitik<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95b36e7 elementor-widget__width-initial elementor-widget-tablet__width-inherit half-text-space-left elementor-widget elementor-widget-text-editor\" data-id=\"95b36e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir werden die Umweltauswirkungen unserer T\u00e4tigkeiten und Produkte minimieren, indem wir<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-480d917 elementor-widget__width-initial elementor-widget-tablet__width-inherit list-items half-text-space-left elementor-widget elementor-widget-text-editor\" data-id=\"480d917\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>die Risiken von Verletzungen und Krankheiten f\u00fcr Mitarbeiter, Umstehende und Benutzer unserer Produkte zu minimieren, auch durch Schulungen. <\/li><li>mit Kunden und Lieferanten zusammenarbeiten, um L\u00f6sungen zu finden, die die Auswirkungen auf die Umwelt reduzieren.<\/li><li>Einsparung von Energie, Wasser und anderen nat\u00fcrlichen Ressourcen, Vermeidung von Umweltverschmutzung sowie Wiederverwendung und Recycling von Ressourcen &#8211; M\u00fclltrennung.<\/li><li>unsere Mitarbeiter zu informieren und zu motivieren, sich in der Umweltarbeit zu engagieren, sich zu beteiligen und Verantwortung zu \u00fcbernehmen.<\/li><li>in \u00dcbereinstimmung mit der geltenden Gesetzgebung arbeiten und mit Beh\u00f6rden und Organisationen kooperieren, damit unser<\/li><li>die Umweltarbeit im Einklang mit den Umweltzielen der Gesellschaft gestaltet wird.<\/li><li>Produkte mit dem Umweltzeichen und Lieferanten mit MLS\/Umweltpolitik werden verwendet.<\/li><li>die Umweltauswirkungen der Produktion zu reduzieren:<\/li><li>Reduzierung des Einsatzes umweltgef\u00e4hrdender (und sch\u00e4dlicher) Chemikalien das Prinzip der Produktauswahl<\/li><li>Verringerung der Abf\u00e4lle aus der Produktion (Chemikalien und Produktionsmaterialien)<\/li><li>eine kontinuierliche Verbesserung in allen Bereichen anstreben, die Umweltauswirkungen verursachen (Einkauf, B\u00fcro\/Verwaltung, Transport und Logistik, Produktion).<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-274f38f\" data-id=\"274f38f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f5352c7 elementor-widget elementor-widget-image\" data-id=\"f5352c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"667\" height=\"500\" src=\"https:\/\/www.stalskog.se\/wp-content\/uploads\/2022\/04\/Miljobild-landet-kompr.jpg\" class=\"attachment-large size-large wp-image-3028\" alt=\"\" srcset=\"https:\/\/www.stalskog.se\/wp-content\/uploads\/2022\/04\/Miljobild-landet-kompr.jpg 667w, https:\/\/www.stalskog.se\/wp-content\/uploads\/2022\/04\/Miljobild-landet-kompr-300x225.jpg 300w, https:\/\/www.stalskog.se\/wp-content\/uploads\/2022\/04\/Miljobild-landet-kompr-600x450.jpg 600w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b79053b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b79053b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6306779\" data-id=\"6306779\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e231d89 elementor-widget elementor-widget-heading\" data-id=\"e231d89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Konfliktmineralien<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e20c345 elementor-widget__width-initial elementor-widget-tablet__width-inherit half-text-space-left elementor-widget elementor-widget-text-editor\" data-id=\"e20c345\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die von der EU-Verordnung \u00fcber Konfliktmineralien erfassten Mineralien sind Zinn, Wolfram, Tantal und Gold (3TG). Die EU hat beschlossen, neue Rechtsvorschriften einzuf\u00fchren, um die verantwortungsvolle Beschaffung von Mineralien durch Importeure zu f\u00f6rdern, die sogenannte EU-Verordnung \u00fcber Konfliktmineralien. Die Gesetzgebung soll sicherstellen, dass Importeure von 3TG-Mineralien diese verantwortungsvoll beschaffen und die R\u00fcckverfolgbarkeit in der Lieferkette verbessern.  <\/p><p>Wir werden uns bem\u00fchen, sicherzustellen, dass unsere Gesch\u00e4fte und Produkte nicht aus Konfliktmineralien aus betroffenen L\u00e4ndern bestehen, indem wir<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80d1a15 elementor-widget__width-initial elementor-widget-tablet__width-inherit list-items half-text-space-left elementor-widget elementor-widget-text-editor\" data-id=\"80d1a15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>eine verantwortungsvolle Beschaffungspolitik f\u00fcr Mineralien einf\u00fchren und diese Anforderung in unserer Lieferkette kommunizieren.<\/li><li>Prozesse und Kontrollen einf\u00fchren und Ma\u00dfnahmen zur Risikominderung umsetzen, um diese Politik zu unterst\u00fctzen.<\/li><li>Materialien von verantwortungsvollen Lieferanten beziehen.<\/li><li>pr\u00fcfen Sie die Dokumentation der Lieferanten auf CMRT.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98f53b6 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"98f53b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das Unternehmen ist Mitglied des REPA-Registers f\u00fcr Verpackungsrecycling.<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2167 alignright\" src=\"https:\/\/www.stalskog.se\/wp-content\/uploads\/2022\/04\/REPA.bmp\" alt=\"\" width=\"50\" height=\"51\"><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b616c81\" data-id=\"b616c81\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>GESCH\u00c4FTSKONZEPT \/ POLITIK Gesch\u00e4ftskonzept Die Produkte des Unternehmens m\u00fcssen die sichersten und erschwinglichsten auf dem Markt sein und als solche wahrgenommen werden. Mit unserem langfristigen Engagement f\u00fcr Produktqualit\u00e4t, Produktentwicklung, Service und Fachwissen geben wir unseren Kunden die Sicherheit, die Ragnar St\u00e5lskog AB zu ihrer ersten Wahl macht. POLITIK Die Qualit\u00e4t sowohl der Produkte als auch [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":3054,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3121","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gesch\u00e4ftskonzept\/Politik &#8211; Ragnar St\u00e5lskog<\/title>\n<meta name=\"description\" content=\"GESCH\u00c4FTSKONZEPT \/ POLITIK Gesch\u00e4ftskonzept Die Produkte des Unternehmens m\u00fcssen die sichersten und erschwinglichsten auf dem Markt sein und als solche\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.stalskog.se\/de\/ueber-uns\/geschaeftsleitbild-grundsaetze\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gesch\u00e4ftskonzept\/Politik &#8211; Ragnar St\u00e5lskog\" \/>\n<meta property=\"og:description\" content=\"GESCH\u00c4FTSKONZEPT \/ POLITIK Gesch\u00e4ftskonzept Die Produkte des Unternehmens m\u00fcssen die sichersten und erschwinglichsten auf dem Markt sein und als solche\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.stalskog.se\/de\/ueber-uns\/geschaeftsleitbild-grundsaetze\/\" \/>\n<meta property=\"og:site_name\" content=\"Ragnar St\u00e5lskog\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-25T14:22:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.stalskog.se\/wp-content\/uploads\/2022\/04\/ISO-9001-SWE_Ragnar_Stalskog_AB.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.stalskog.se\\\/de\\\/ueber-uns\\\/geschaeftsleitbild-grundsaetze\\\/\",\"url\":\"https:\\\/\\\/www.stalskog.se\\\/de\\\/ueber-uns\\\/geschaeftsleitbild-grundsaetze\\\/\",\"name\":\"Gesch\u00e4ftskonzept\\\/Politik &#8211; Ragnar St\u00e5lskog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stalskog.se\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.stalskog.se\\\/de\\\/ueber-uns\\\/geschaeftsleitbild-grundsaetze\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stalskog.se\\\/de\\\/ueber-uns\\\/geschaeftsleitbild-grundsaetze\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.stalskog.se\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/ISO-9001-SWE_Ragnar_Stalskog_AB.png\",\"datePublished\":\"2022-04-19T09:23:24+00:00\",\"dateModified\":\"2025-08-25T14:22:36+00:00\",\"description\":\"GESCH\u00c4FTSKONZEPT \\\/ POLITIK Gesch\u00e4ftskonzept Die Produkte des Unternehmens m\u00fcssen die sichersten und erschwinglichsten auf dem Markt sein und als solche\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.stalskog.se\\\/de\\\/ueber-uns\\\/geschaeftsleitbild-grundsaetze\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.stalskog.se\\\/de\\\/ueber-uns\\\/geschaeftsleitbild-grundsaetze\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.stalskog.se\\\/de\\\/ueber-uns\\\/geschaeftsleitbild-grundsaetze\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.stalskog.se\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/ISO-9001-SWE_Ragnar_Stalskog_AB.png\",\"contentUrl\":\"https:\\\/\\\/www.stalskog.se\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/ISO-9001-SWE_Ragnar_Stalskog_AB.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.stalskog.se\\\/de\\\/ueber-uns\\\/geschaeftsleitbild-grundsaetze\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\\\/\\\/www.stalskog.se\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00fcber uns\",\"item\":\"https:\\\/\\\/www.stalskog.se\\\/de\\\/om-oss\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gesch\u00e4ftskonzept\\\/Politik\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.stalskog.se\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.stalskog.se\\\/de\\\/\",\"name\":\"Ragnar St\u00e5lskog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.stalskog.se\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.stalskog.se\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.stalskog.se\\\/de\\\/#organization\",\"name\":\"Ragnar St\u00e5lskog\",\"url\":\"https:\\\/\\\/www.stalskog.se\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.stalskog.se\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.stalskog.se\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/logo_o.png\",\"contentUrl\":\"https:\\\/\\\/www.stalskog.se\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/logo_o.png\",\"width\":410,\"height\":99,\"caption\":\"Ragnar St\u00e5lskog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stalskog.se\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gesch\u00e4ftskonzept\/Politik &#8211; Ragnar St\u00e5lskog","description":"GESCH\u00c4FTSKONZEPT \/ POLITIK Gesch\u00e4ftskonzept Die Produkte des Unternehmens m\u00fcssen die sichersten und erschwinglichsten auf dem Markt sein und als solche","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.stalskog.se\/de\/ueber-uns\/geschaeftsleitbild-grundsaetze\/","og_locale":"de_DE","og_type":"article","og_title":"Gesch\u00e4ftskonzept\/Politik &#8211; Ragnar St\u00e5lskog","og_description":"GESCH\u00c4FTSKONZEPT \/ POLITIK Gesch\u00e4ftskonzept Die Produkte des Unternehmens m\u00fcssen die sichersten und erschwinglichsten auf dem Markt sein und als solche","og_url":"https:\/\/www.stalskog.se\/de\/ueber-uns\/geschaeftsleitbild-grundsaetze\/","og_site_name":"Ragnar St\u00e5lskog","article_modified_time":"2025-08-25T14:22:36+00:00","og_image":[{"url":"https:\/\/www.stalskog.se\/wp-content\/uploads\/2022\/04\/ISO-9001-SWE_Ragnar_Stalskog_AB.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.stalskog.se\/de\/ueber-uns\/geschaeftsleitbild-grundsaetze\/","url":"https:\/\/www.stalskog.se\/de\/ueber-uns\/geschaeftsleitbild-grundsaetze\/","name":"Gesch\u00e4ftskonzept\/Politik &#8211; Ragnar St\u00e5lskog","isPartOf":{"@id":"https:\/\/www.stalskog.se\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.stalskog.se\/de\/ueber-uns\/geschaeftsleitbild-grundsaetze\/#primaryimage"},"image":{"@id":"https:\/\/www.stalskog.se\/de\/ueber-uns\/geschaeftsleitbild-grundsaetze\/#primaryimage"},"thumbnailUrl":"https:\/\/www.stalskog.se\/wp-content\/uploads\/2022\/04\/ISO-9001-SWE_Ragnar_Stalskog_AB.png","datePublished":"2022-04-19T09:23:24+00:00","dateModified":"2025-08-25T14:22:36+00:00","description":"GESCH\u00c4FTSKONZEPT \/ POLITIK Gesch\u00e4ftskonzept Die Produkte des Unternehmens m\u00fcssen die sichersten und erschwinglichsten auf dem Markt sein und als solche","breadcrumb":{"@id":"https:\/\/www.stalskog.se\/de\/ueber-uns\/geschaeftsleitbild-grundsaetze\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.stalskog.se\/de\/ueber-uns\/geschaeftsleitbild-grundsaetze\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.stalskog.se\/de\/ueber-uns\/geschaeftsleitbild-grundsaetze\/#primaryimage","url":"https:\/\/www.stalskog.se\/wp-content\/uploads\/2022\/04\/ISO-9001-SWE_Ragnar_Stalskog_AB.png","contentUrl":"https:\/\/www.stalskog.se\/wp-content\/uploads\/2022\/04\/ISO-9001-SWE_Ragnar_Stalskog_AB.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.stalskog.se\/de\/ueber-uns\/geschaeftsleitbild-grundsaetze\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/www.stalskog.se\/de\/"},{"@type":"ListItem","position":2,"name":"\u00fcber uns","item":"https:\/\/www.stalskog.se\/de\/om-oss\/"},{"@type":"ListItem","position":3,"name":"Gesch\u00e4ftskonzept\/Politik"}]},{"@type":"WebSite","@id":"https:\/\/www.stalskog.se\/de\/#website","url":"https:\/\/www.stalskog.se\/de\/","name":"Ragnar St\u00e5lskog","description":"","publisher":{"@id":"https:\/\/www.stalskog.se\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.stalskog.se\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.stalskog.se\/de\/#organization","name":"Ragnar St\u00e5lskog","url":"https:\/\/www.stalskog.se\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.stalskog.se\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.stalskog.se\/wp-content\/uploads\/2022\/03\/logo_o.png","contentUrl":"https:\/\/www.stalskog.se\/wp-content\/uploads\/2022\/03\/logo_o.png","width":410,"height":99,"caption":"Ragnar St\u00e5lskog"},"image":{"@id":"https:\/\/www.stalskog.se\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.stalskog.se\/de\/wp-json\/wp\/v2\/pages\/3121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stalskog.se\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.stalskog.se\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.stalskog.se\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stalskog.se\/de\/wp-json\/wp\/v2\/comments?post=3121"}],"version-history":[{"count":6,"href":"https:\/\/www.stalskog.se\/de\/wp-json\/wp\/v2\/pages\/3121\/revisions"}],"predecessor-version":[{"id":15200,"href":"https:\/\/www.stalskog.se\/de\/wp-json\/wp\/v2\/pages\/3121\/revisions\/15200"}],"up":[{"embeddable":true,"href":"https:\/\/www.stalskog.se\/de\/wp-json\/wp\/v2\/pages\/3054"}],"wp:attachment":[{"href":"https:\/\/www.stalskog.se\/de\/wp-json\/wp\/v2\/media?parent=3121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}